{"id":38748,"date":"2021-08-25T12:01:12","date_gmt":"2021-08-25T12:01:12","guid":{"rendered":"https:\/\/www.lasantamarket.com\/shop\/dessuadora\/"},"modified":"2021-08-26T10:41:08","modified_gmt":"2021-08-26T10:41:08","slug":"dessuadora-noi-new-collection","status":"publish","type":"product","link":"https:\/\/www.lasantamarket.com\/ca\/shop\/dessuadora-noi-new-collection\/","title":{"rendered":"Dessuadora noi New Collection"},"content":{"rendered":"<p>Dessuadora de noi de cot\u00f3 100% natural.<\/p>\n<div class=\"\">Teixit suau i c\u00f2mode.<\/div>\n<p><span class=\"shop_small\"><strong>* Venda sense entrega a domicili.<\/strong><br \/>\n<strong>Nom\u00e9s recollida a La Santa de 18h a 23h del 16\/07\/2021 al 29\/08\/2021.<\/strong><br \/>\nDespr\u00e9s de realitzar la compra rebr\u00e0s un email de confirmaci\u00f3 de la mateixa i l\u2019ID per fer la recollida al nostre espai.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dessuadora de noi de cot\u00f3 100% natural.<\/p>\n<div class=\"\">Teixit suau i c\u00f2mode.<\/div>\n<p><span class=\"shop_small\"><strong>* Venda sense entrega a domicili.<\/strong><br \/>\n<strong>Nom\u00e9s recollida a La Santa de 18h a 23h del 16\/07\/2021 al 29\/08\/2021.<\/strong><br \/>\nDespr\u00e9s de realitzar la compra rebr\u00e0s un email de confirmaci\u00f3 de la mateixa i l\u2019ID per fer la recollida al nostre espai.<\/span><\/p>\n","protected":false},"featured_media":38807,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[271,254],"product_tag":[],"class_list":["post-38748","product","type-product","status-publish","has-post-thumbnail","product_cat-new-collection-ca","product_cat-nois","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lasantamarket.com\/ca\/wp-json\/wp\/v2\/product\/38748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasantamarket.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.lasantamarket.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasantamarket.com\/ca\/wp-json\/wp\/v2\/media\/38807"}],"wp:attachment":[{"href":"https:\/\/www.lasantamarket.com\/ca\/wp-json\/wp\/v2\/media?parent=38748"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.lasantamarket.com\/ca\/wp-json\/wp\/v2\/product_brand?post=38748"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.lasantamarket.com\/ca\/wp-json\/wp\/v2\/product_cat?post=38748"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.lasantamarket.com\/ca\/wp-json\/wp\/v2\/product_tag?post=38748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}